{"id":21961,"date":"2023-10-03T16:13:38","date_gmt":"2023-10-03T14:13:38","guid":{"rendered":"https:\/\/ht-ost.com\/?p=21961"},"modified":"2023-10-03T16:13:39","modified_gmt":"2023-10-03T14:13:39","slug":"eine-suppenkueche-fuer-die-letzte-sowjetrepublik","status":"publish","type":"post","link":"https:\/\/ht-ost.com\/de\/eine-suppenkueche-fuer-die-letzte-sowjetrepublik\/","title":{"rendered":"Eine Suppenk\u00fcche f\u00fcr die \u201eletzte Sowjetrepublik\u201c"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"21961\" class=\"elementor elementor-21961\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c02d3f3 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c02d3f3\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b27e4e\" data-id=\"7b27e4e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-19dac02 elementor-widget elementor-widget-image\" data-id=\"19dac02\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"519\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091139_722_web-e1696335329741-1024x519.jpg\" class=\"attachment-large size-large wp-image-22033\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091139_722_web-e1696335329741-1024x519.jpg 1024w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091139_722_web-e1696335329741-300x152.jpg 300w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091139_722_web-e1696335329741-768x389.jpg 768w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091139_722_web-e1696335329741-1536x778.jpg 1536w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091139_722_web-e1696335329741.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e8bf51 elementor-widget elementor-widget-text-editor\" data-id=\"0e8bf51\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Der kleine De-facto-Staat Transnistrien war lange Zeit Teil der damaligen Sowjetrepublik Moldau und befindet sich seit dem Zusammenbruch der Sowjetunion in einem bis heute eingefrorenen Konflikt mit der offiziellen Regierung Moldawiens &#8211; zum Leidwesen beider Seiten: <br \/>Moldawien hat keinen Zugriff auf sein wirtschaftlich st\u00e4rkstes Gebiet und Transnistrien kann aus seiner Industrie wenig Nutzen ziehen, da es mit Ausnahme von Russland von keinem anderem Staat anerkannt wird. <br \/>U.a. deshalb spitzt sich sowohl die \u00f6konomische als auch die soziale Situation immer mehr zu: Viele Menschen haben ihre Jobs verloren oder m\u00fcssen f\u00fcr sehr geringe L\u00f6hne arbeiten, was zu gro\u00dfen Auswanderungswellen f\u00fchrt. Zur\u00fcck bleiben oft Senioren, Kinder und andere Menschen, die stark auf die Hilfe anderer angewiesen sind.<\/p><p><strong>Die Christliche Gemeinde in Tiraspol sieht die Not der Menschen<\/strong><br \/>Die Gemeinde \u201eBotschaft des Evangeliums\u201c befindet sich in einem der \u00e4rmeren Viertel der \u201eHauptstadt\u201c Tiraspol. <br \/>Pastor Leonid Schwetz berichtet: <br \/>Wir als Gemeinde haben besonders Kinder und sozial schwache Menschen auf dem Herzen und wollen m\u00f6glichst viele Angebote schaffen, um ihnen zu helfen. So arbeiten wir schon lange mit diesen Kindern und teilen Essen an hilfsbed\u00fcrftige Menschen aus. In der Vergangenheit bekamen wir zunehmend ein Platzproblem, weshalb wir damit begonnen haben, einen Anbau neben unserem Gemeindehaus zu errichten, in dessen Erdgeschoss ein Speisesaal entstehen soll. Das gibt uns die M\u00f6glichkeit ein- bis zweimal w\u00f6chentlich warme Mahlzeiten f\u00fcr Kinder aus armen Familien anzubieten. Zudem kann der Speisesaal dann auch f\u00fcr regionale Jugendtreffen oder Gemeindeveranstaltungen genutzt werden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0a53039 uael-img-grid__column-2 uael-img-grid-mobile__column-1 uael-img-grid-tablet__column-3 uael-ins-normal elementor-widget elementor-widget-uael-image-gallery\" data-id=\"0a53039\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;gallery_columns&quot;:&quot;2&quot;,&quot;gallery_columns_mobile&quot;:&quot;1&quot;,&quot;gallery_columns_tablet&quot;:&quot;3&quot;,&quot;column_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;column_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;column_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:20,&quot;sizes&quot;:[]},&quot;row_gap_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;row_gap_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"uael-image-gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"uael-gallery-parent uael-caption- uael-gallery-unjustified\"><div class=\"uael-img-gallery-wrap uael-img-masonry-wrap uael-img-grid-masonry-wrap uael-masonry\" data-filter-default=\"All\"><div class=\"uael-grid-item  uael-img-gallery-item-1\"><div class=\"uael-grid-item-content\"><figure class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG-20230803-WA0001_web-1024x683.jpg\" class=\"attachment-large size-large wp-image-22053\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG-20230803-WA0001_web-1024x683.jpg 1024w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG-20230803-WA0001_web-300x200.jpg 300w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG-20230803-WA0001_web-768x512.jpg 768w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG-20230803-WA0001_web.jpg 1498w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/figure><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-2\"><div class=\"uael-grid-item-content\"><figure class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091200_190_web-1024x682.jpg\" class=\"attachment-large size-large wp-image-22048\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091200_190_web-1024x682.jpg 1024w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091200_190_web-300x200.jpg 300w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091200_190_web-768x512.jpg 768w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091200_190_web-1536x1024.jpg 1536w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091200_190_web.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/figure><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-3\"><div class=\"uael-grid-item-content\"><figure class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091144_375_web-1024x682.jpg\" class=\"attachment-large size-large wp-image-22038\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091144_375_web-1024x682.jpg 1024w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091144_375_web-300x200.jpg 300w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091144_375_web-768x512.jpg 768w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091144_375_web-1536x1024.jpg 1536w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091144_375_web.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/figure><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-4\"><div class=\"uael-grid-item-content\"><figure class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091138_992_web-1024x682.jpg\" class=\"attachment-large size-large wp-image-22028\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091138_992_web-1024x682.jpg 1024w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091138_992_web-300x200.jpg 300w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091138_992_web-768x512.jpg 768w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091138_992_web-1536x1024.jpg 1536w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091138_992_web.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/figure><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-5\"><div class=\"uael-grid-item-content\"><figure class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091132_637_web-1024x682.jpg\" class=\"attachment-large size-large wp-image-22023\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091132_637_web-1024x682.jpg 1024w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091132_637_web-300x200.jpg 300w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091132_637_web-768x512.jpg 768w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091132_637_web-1536x1024.jpg 1536w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091132_637_web.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/figure><\/div><\/div><div class=\"uael-grid-item  uael-img-gallery-item-6\"><div class=\"uael-grid-item-content\"><figure class=\"uael-grid-img uael-grid-gallery-img uael-ins-hover elementor-clickable\"><div class=\"uael-grid-img-thumbnail uael-ins-target\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091127_280_web-1024x682.jpg\" class=\"attachment-large size-large wp-image-22018\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091127_280_web-1024x682.jpg 1024w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091127_280_web-300x200.jpg 300w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091127_280_web-768x512.jpg 768w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091127_280_web-1536x1024.jpg 1536w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/IMG_20230919_091127_280_web.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/div><div class=\"uael-grid-img-overlay\"><\/div><\/figure><\/div><\/div><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bde7aa8 elementor-widget elementor-widget-text-editor\" data-id=\"bde7aa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<strong>Treffpunkt und Hilfsangebot f\u00fcr Obdachlose<\/strong><p>Im 1. Stock sollen zus\u00e4tzlich drei R\u00e4ume entstehen, von denen zwei als Gruppenr\u00e4ume f\u00fcr die Sonntagsschule und anderen Kindergruppen vorgesehen sind. Der dritte Raum ist f\u00fcr die Arbeit mit Obdachlosen bestimmt und soll mehrere Funktionen erf\u00fcllen: Zum einen soll er als Wohnraum f\u00fcr ein Ehepaar dienen, die fr\u00fcher obdachlos waren, zum Glauben kamen und nun gern selbst mit Obdachlosen arbeiten m\u00f6chten. <br>Dar\u00fcber hinaus soll der Raum als Treffpunkt dienen, wo sich Obdachlose waschen und auf eine Reha vorbereiten k\u00f6nnen. Das Ehepaar unterst\u00fctzt sie bei dem gesamten Prozess und hilft beispielsweise beim Ausf\u00fcllen der n\u00f6tigen Dokumente. <br>Durch den bisherigen Dienst konnten wir bereits immer wieder sehen, wie Gott Menschen ver\u00e4ndert: <br>Manche h\u00f6ren auf zu trinken, erholen sich k\u00f6rperlich wie auch geistig und fangen teilweise an, die Gottesdienste zu besuchen.<br>Unser Wunsch ist es, den Bau des Nebengeb\u00e4udes vor Einbruch der K\u00e4lte fertigzustellen. Daf\u00fcr m\u00fcssen noch Fenster und T\u00fcren eingesetzt sowie die Heizung installiert werden. Danach kann auch bei niedrigen Au\u00dfentemperaturen der Innenausbau fortgef\u00fchrt werden, sodass bis Jahresende zumindest ein Gruppenraum nutzbar ist.<\/p>\n<p>Gerade in diesen schwierigen Zeiten, die unser Land momentan erlebt, sind wir dennoch als Christen vereint. <br>Es gibt noch viel Arbeit, aber gemeinsam k\u00f6nnen wir es schaffen.<\/p>\n<p>F\u00fcr den Abschluss des Rohbaus fehlen allerdings noch etwa 3000\u20ac. Wir sind f\u00fcr jede Unterst\u00fctzung dankbar. <br>Bei \u00dcberweisung bitte Verwendungszweck \u201eSuppenk\u00fcche Tiraspol\u201c angeben.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d40f30 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d40f30\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-b25a09c\" data-id=\"b25a09c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3fa9797 elementor-widget elementor-widget-text-editor\" data-id=\"3fa9797\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das ist Vadim. <br>Er ist 38 Jahre alt, von denen er 21 hinter Gittern verbrachte. <br>Zwischen seinen Haftaufenthalten kam er regelm\u00e4\u00dfig zum Essen zu uns und unterhielt sich mit den Pastoren. Nun bewegte ihn der Heilige Geist dazu, uns um Hilfe zu bitten, seinem s\u00fcndigen Umfeld, in dem er zugrunde gegangen ist, zu entfliehen. Momentan bereiten wir alles daf\u00fcr vor, um ihn in ein Rehabilitationszentrum zu schicken. All dies findet im Rahmen unseres Sozialen Dienstes statt \u2013 preist unseren Herrn f\u00fcr die Gelegenheit, diesen Menschen zu helfen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-80d3dbb\" data-id=\"80d3dbb\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d84b60 elementor-widget elementor-widget-image\" data-id=\"8d84b60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Vadim_web-1024x1024.jpg\" class=\"attachment-large size-large wp-image-22003\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Vadim_web-1024x1024.jpg 1024w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Vadim_web-300x300.jpg 300w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Vadim_web-150x150.jpg 150w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Vadim_web-768x768.jpg 768w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Vadim_web.jpg 1067w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-74f9653 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"74f9653\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c5b0405\" data-id=\"c5b0405\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5328c59 elementor-widget elementor-widget-image\" data-id=\"5328c59\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"886\" height=\"885\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Ljuda_web.jpg\" class=\"attachment-large size-large wp-image-22058\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Ljuda_web.jpg 886w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Ljuda_web-300x300.jpg 300w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Ljuda_web-150x150.jpg 150w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Ljuda_web-768x767.jpg 768w\" sizes=\"(max-width: 886px) 100vw, 886px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-eef476d\" data-id=\"eef476d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2020769 elementor-widget elementor-widget-text-editor\" data-id=\"2020769\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das ist Ljuda. <br \/>Sie besucht seit \u00fcber einem Jahr unsere sozialen Angebote. <br \/>Fr\u00fcher verkaufte und konsumierte sie viel Vodka, doch als sie begann zu unseren Essensausgaben zu kommen und Gottes Wort zu h\u00f6ren, begann sie sich zu ver\u00e4ndern. <br \/>Sie verkauft nun keinen Alkohol mehr und wir haben sie schon lange nicht mehr betrunken gesehen. Sie sieht viel besser und freundlicher aus und begann, sich wieder mehr ihrer Familien und ihren Enkeln zu widmen. Wir hoffen, sie bald in unseren Gottesdiensten zu sehen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4d28fa8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4d28fa8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7d2e12f\" data-id=\"7d2e12f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e4316b5 elementor-widget elementor-widget-text-editor\" data-id=\"e4316b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das ist Andrej.<br \/>Er besucht schon lange unsere sozialen Angebote. <br \/>Fr\u00fcher hat er sehr stark geraucht und getrunken, sodass er heute nur noch mit einer Gehhilfe laufen kann. Inzwischen ist er ein anderer Mensch geworden: <br \/>Er trinkt nicht mehr, ist kontaktfreudig, umg\u00e4nglich und achtet mehr auf sich selbst. <br \/>Au\u00dferdem zieht es ihn immer mehr zu gl\u00e4ubigen Menschen. Preist den Herrn, dass Gott Menschen so ver\u00e4ndert.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1dc673a\" data-id=\"1dc673a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-53c92fc elementor-widget elementor-widget-image\" data-id=\"53c92fc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Andrej_web-1024x1024.jpg\" class=\"attachment-large size-large wp-image-22008\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Andrej_web-1024x1024.jpg 1024w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Andrej_web-300x300.jpg 300w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Andrej_web-150x150.jpg 150w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Andrej_web-768x768.jpg 768w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Andrej_web.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fa4cbc8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fa4cbc8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-43f833e\" data-id=\"43f833e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b73f77 elementor-widget elementor-widget-image\" data-id=\"8b73f77\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"888\" height=\"888\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Ljudmilla_web.jpg\" class=\"attachment-large size-large wp-image-22063\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Ljudmilla_web.jpg 888w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Ljudmilla_web-300x300.jpg 300w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Ljudmilla_web-150x150.jpg 150w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Ljudmilla_web-768x768.jpg 768w\" sizes=\"(max-width: 888px) 100vw, 888px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-3a78c1b\" data-id=\"3a78c1b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a11273 elementor-widget elementor-widget-text-editor\" data-id=\"6a11273\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das ist Ljudmilla.<br \/>Sie kommt seit \u00fcber einem Jahr zu unseren sozialen Angeboten. <br \/>Fr\u00fcher trank und rauchte sie sehr stark, doch seit drei Monaten ist sie \u201etrocken\u201c und kommt auch regelm\u00e4\u00dfig in unsere Sonntagsgottesdienste. <br \/>Sie ist sehr gerne in unserer Gemeinde, h\u00f6rt das Wort Gottes und unterh\u00e4lt sich mit den Gemeindemitgliedern. <br \/>Auch ihr Aussehen hat sich stark ver\u00e4ndert: Sie achtet mehr auf sich. Preist den Herrn!<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8912a66 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8912a66\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-d54204f\" data-id=\"d54204f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-38f36a8 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"38f36a8\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a941b0\" data-id=\"0a941b0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95d92f1 elementor-widget elementor-widget-spacer\" data-id=\"95d92f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-07111b1 elementor-widget elementor-widget-heading\" data-id=\"07111b1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Zeitschrift 2023 Nr.4<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f395c2a elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f395c2a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77aa195 uael-posts-thumbnail-ratio elementor-widget elementor-widget-uael-posts\" data-id=\"77aa195\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;classic_slides_to_show&quot;:3,&quot;classic_slides_to_show_tablet&quot;:2,&quot;classic_slides_to_show_mobile&quot;:1}\" data-widget_type=\"uael-posts.classic\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"uael-post__header\">\n\t\t\t\t\t<\/div>\n\t\t<div class=\"uael-post__body\">\n\t\t\t\n\t\t\n\t\t<div class=\"uael-blog-terms-position-above_content uael-post-image-top uael-post-grid uael-posts\" data-query-type=\"custom\" data-structure=\"carousel\" data-layout=\"\" data-page=\"21961\" data-skin=\"classic\" data-filter-default=\"\" data-offset-top=\"30\" data-post_slider=\"{&quot;slidesToShow&quot;:3,&quot;slidesToScroll&quot;:1,&quot;autoplaySpeed&quot;:2500,&quot;autoplay&quot;:true,&quot;infinite&quot;:true,&quot;pauseOnHover&quot;:false,&quot;speed&quot;:2000,&quot;arrows&quot;:false,&quot;dots&quot;:true,&quot;rtl&quot;:false,&quot;prevArrow&quot;:&quot;&lt;button type=\\&quot;button\\&quot; data-role=\\&quot;none\\&quot; class=\\&quot;slick-prev\\&quot; aria-label=\\&quot;Previous\\&quot; tabindex=\\&quot;0\\&quot; role=\\&quot;button\\&quot;&gt;&lt;i class=\\&quot;fa fa-angle-left\\&quot;&gt;&lt;\\\/i&gt;&lt;\\\/button&gt;&quot;,&quot;nextArrow&quot;:&quot;&lt;button type=\\&quot;button\\&quot; data-role=\\&quot;none\\&quot; class=\\&quot;slick-next\\&quot; aria-label=\\&quot;Next\\&quot; tabindex=\\&quot;0\\&quot; role=\\&quot;button\\&quot;&gt;&lt;i class=\\&quot;fa fa-angle-right\\&quot;&gt;&lt;\\\/i&gt;&lt;\\\/button&gt;&quot;,&quot;responsive&quot;:[{&quot;breakpoint&quot;:1024,&quot;settings&quot;:{&quot;slidesToShow&quot;:2,&quot;slidesToScroll&quot;:2}},{&quot;breakpoint&quot;:767,&quot;settings&quot;:{&quot;slidesToShow&quot;:1,&quot;slidesToScroll&quot;:1}}]}\" data-equal-height=\"yes\" data-post-count=\"7\">\n\n\t\t\t\t\t\t\t<div class=\"uael-post-grid__inner uael-post__columns-3 uael-post__columns-tablet-2 uael-post__columns-mobile-1\">\n\t\t\t\n<div class=\"uael-post-wrapper   weihnachtsp\u00e4ckchen-23\/24 \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/ht-ost.com\/de\/geschenke-von-oben-wpa-2023-24\/\" target=\"_self\" title=\"Geschenke von oben? &#8211; WPA 2023\/24\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild_md-ua1.jpg\" class=\"attachment-medium_large size-medium_large wp-image-21972\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild_md-ua1.jpg 750w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild_md-ua1-300x200.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t\t\t<div class=\"uael-post__terms-wrap\"><span class=\"uael-post__terms\"><span class=\"uael-listing__terms-link\">Weihnachtsp\u00e4ckchen 23\/24<\/span><\/span><\/div>\n\t\t\t\t\t\t<h4 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/ht-ost.com\/de\/geschenke-von-oben-wpa-2023-24\/\" target=\"_self\">\n\t\t\t\tGeschenke von oben? &#8211; WPA 2023\/24\t\t\t<\/a>\n\n\t\t\t\t<\/h4>\n\t\t\t\t\t<div class=\"uael-post__meta-data\">\n\t\t\t\t\t<span class=\"uael-post__date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa fa-calendar\"><\/i>\t\t\t\t\t\t\t\t\t\n\t\t\t5. Oktober 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div class=\"uael-post__excerpt\">\n\t\t\t\u201eJede gute Gabe und jedes vollkommene Geschenk kommt von oben herab, von dem Vater der Lichter.\u201c Jakobus 1,17 Zwar ist es bei uns dieses Jahr ...\t\t<\/div>\n\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/ht-ost.com\/de\/geschenke-von-oben-wpa-2023-24\/\" target=\"_self\" aria-labelledby=\"uael-post-22213\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=uael-post-22213>Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   missionare \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/ht-ost.com\/de\/unsere-neuen-mitarbeiter\/\" target=\"_self\" title=\"Unsere neuen Mitarbeiter\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild3_md.jpg\" class=\"attachment-medium_large size-medium_large wp-image-21982\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild3_md.jpg 750w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild3_md-300x200.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t\t\t<div class=\"uael-post__terms-wrap\"><span class=\"uael-post__terms\"><span class=\"uael-listing__terms-link\">Missionare<\/span><\/span><\/div>\n\t\t\t\t\t\t<h4 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/ht-ost.com\/de\/unsere-neuen-mitarbeiter\/\" target=\"_self\">\n\t\t\t\tUnsere neuen Mitarbeiter\t\t\t<\/a>\n\n\t\t\t\t<\/h4>\n\t\t\t\t\t<div class=\"uael-post__meta-data\">\n\t\t\t\t\t<span class=\"uael-post__date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa fa-calendar\"><\/i>\t\t\t\t\t\t\t\t\t\n\t\t\t3. Oktober 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div class=\"uael-post__excerpt\">\n\t\t\tSeit dem 1. September 2023 sind wir neue Mitarbeiter bei Hoffnungstr\u00e4ger Ost (HTO) und freuen uns darauf, Gott zu dienen und zu sehen, wie er ...\t\t<\/div>\n\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/ht-ost.com\/de\/unsere-neuen-mitarbeiter\/\" target=\"_self\" aria-labelledby=\"uael-post-22223\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=uael-post-22223>Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   editorial \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/ht-ost.com\/de\/haben-wir-das-werfen-gelernt\/\" target=\"_self\" title=\"Haben wir das Werfen gelernt?\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"333\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Editorial_web2.jpg\" class=\"attachment-medium_large size-medium_large wp-image-21992\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Editorial_web2.jpg 500w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/Editorial_web2-300x200.jpg 300w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t\t\t<div class=\"uael-post__terms-wrap\"><span class=\"uael-post__terms\"><span class=\"uael-listing__terms-link\">Editorial<\/span><\/span><\/div>\n\t\t\t\t\t\t<h4 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/ht-ost.com\/de\/haben-wir-das-werfen-gelernt\/\" target=\"_self\">\n\t\t\t\tHaben wir das Werfen gelernt?\t\t\t<\/a>\n\n\t\t\t\t<\/h4>\n\t\t\t\t\t<div class=\"uael-post__meta-data\">\n\t\t\t\t\t<span class=\"uael-post__date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa fa-calendar\"><\/i>\t\t\t\t\t\t\t\t\t\n\t\t\t3. Oktober 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div class=\"uael-post__excerpt\">\n\t\t\tLiebe Missionsfreunde, ich muss zugeben, bei den Bundesjugendspielen in der Schule fiel mir das Werfen nicht immer leicht. Damals kam es auf die richtige Wurftechnik ...\t\t<\/div>\n\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/ht-ost.com\/de\/haben-wir-das-werfen-gelernt\/\" target=\"_self\" aria-labelledby=\"uael-post-22185\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=uael-post-22185>Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   evangelisation suppenk\u00fcchen \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/ht-ost.com\/de\/eine-suppenkueche-fuer-die-letzte-sowjetrepublik\/\" target=\"_self\" title=\"Eine Suppenk\u00fcche f\u00fcr die \u201eletzte Sowjetrepublik\u201c\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild1_md.jpg\" class=\"attachment-medium_large size-medium_large wp-image-21977\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild1_md.jpg 750w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild1_md-300x200.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t\t\t<div class=\"uael-post__terms-wrap\"><span class=\"uael-post__terms\"><span class=\"uael-listing__terms-link\">Evangelisation<\/span><\/span><\/div>\n\t\t\t\t\t\t<h4 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/ht-ost.com\/de\/eine-suppenkueche-fuer-die-letzte-sowjetrepublik\/\" target=\"_self\">\n\t\t\t\tEine Suppenk\u00fcche f\u00fcr die \u201eletzte Sowjetrepublik\u201c\t\t\t<\/a>\n\n\t\t\t\t<\/h4>\n\t\t\t\t\t<div class=\"uael-post__meta-data\">\n\t\t\t\t\t<span class=\"uael-post__date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa fa-calendar\"><\/i>\t\t\t\t\t\t\t\t\t\n\t\t\t3. Oktober 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div class=\"uael-post__excerpt\">\n\t\t\tDer kleine De-facto-Staat Transnistrien war lange Zeit Teil der damaligen Sowjetrepublik Moldau und befindet sich seit dem Zusammenbruch der Sowjetunion in einem bis heute eingefrorenen ...\t\t<\/div>\n\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/ht-ost.com\/de\/eine-suppenkueche-fuer-die-letzte-sowjetrepublik\/\" target=\"_self\" aria-labelledby=\"uael-post-21961\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=uael-post-21961>Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   patenschaften \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/ht-ost.com\/de\/aus-dem-patenschaftsprojekt\/\" target=\"_self\" title=\"Aus dem Patenschaftsprojekt &#8230;\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild_md.jpg\" class=\"attachment-medium_large size-medium_large wp-image-21962\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild_md.jpg 750w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild_md-300x200.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t\t\t<div class=\"uael-post__terms-wrap\"><span class=\"uael-post__terms\"><span class=\"uael-listing__terms-link\">Patenschaften<\/span><\/span><\/div>\n\t\t\t\t\t\t<h4 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/ht-ost.com\/de\/aus-dem-patenschaftsprojekt\/\" target=\"_self\">\n\t\t\t\tAus dem Patenschaftsprojekt &#8230;\t\t\t<\/a>\n\n\t\t\t\t<\/h4>\n\t\t\t\t\t<div class=\"uael-post__meta-data\">\n\t\t\t\t\t<span class=\"uael-post__date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa fa-calendar\"><\/i>\t\t\t\t\t\t\t\t\t\n\t\t\t1. Oktober 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div class=\"uael-post__excerpt\">\n\t\t\tNeue Wege der Evangelisation in einem kriegszerr\u00fctteten Land Stellvertretend f\u00fcr hunderte Patenkinder in der Ukraine, die seit Beginn des Krieges eine schwere Zeit durchmachen, m\u00f6chten ...\t\t<\/div>\n\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/ht-ost.com\/de\/aus-dem-patenschaftsprojekt\/\" target=\"_self\" aria-labelledby=\"uael-post-22195\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=uael-post-22195>Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   kinderfreizeiten \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/ht-ost.com\/de\/kinderfreizeit-in-izium\/\" target=\"_self\" title=\"Kinderfreizeit in Izium\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild_md-ua.jpg\" class=\"attachment-medium_large size-medium_large wp-image-21967\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild_md-ua.jpg 750w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild_md-ua-300x200.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t\t\t<div class=\"uael-post__terms-wrap\"><span class=\"uael-post__terms\"><span class=\"uael-listing__terms-link\">Kinderfreizeiten<\/span><\/span><\/div>\n\t\t\t\t\t\t<h4 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/ht-ost.com\/de\/kinderfreizeit-in-izium\/\" target=\"_self\">\n\t\t\t\tKinderfreizeit in Izium\t\t\t<\/a>\n\n\t\t\t\t<\/h4>\n\t\t\t\t\t<div class=\"uael-post__meta-data\">\n\t\t\t\t\t<span class=\"uael-post__date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa fa-calendar\"><\/i>\t\t\t\t\t\t\t\t\t\n\t\t\t25. September 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div class=\"uael-post__excerpt\">\n\t\t\tIn diesem Jahr konnten im Sommer wieder viele Kinderfreizeiten durchgef\u00fchrt werden \u2013 allein in Moldawien waren es diesmal 21 Freizeiten, bei denen mehr als 1000 ...\t\t<\/div>\n\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/ht-ost.com\/de\/kinderfreizeit-in-izium\/\" target=\"_self\" aria-labelledby=\"uael-post-22075\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=uael-post-22075>Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\n<div class=\"uael-post-wrapper   evangelisation \">\n\t<div class=\"uael-post__bg-wrap uael-bg-wrap-disabled \">\n\n\t\t\t\t\n\t\t<div class=\"uael-post__inner-wrap uael-inner-wrap-disabled\">\n\n\t\t\t\t<div class=\"uael-post__thumbnail\">\n\t\t\t\n\t\t\t<a href=\"https:\/\/ht-ost.com\/de\/spielplatz-holercani\/\" target=\"_self\" title=\"Spielplatz Holercani\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"500\" src=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild4_md.jpg\" class=\"attachment-medium_large size-medium_large wp-image-21987\" alt=\"\" srcset=\"https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild4_md.jpg 750w, https:\/\/ht-ost.com\/wp-content\/uploads\/2023\/10\/20231003001_beitragsbild4_md-300x200.jpg 300w\" sizes=\"(max-width: 750px) 100vw, 750px\" \/><\/a>\n\t\t\t\t\t<\/div>\n\t\t\n\t\t\t\n\t\t\t<div class=\"uael-post__content-wrap uael-content-wrap-disabled\">\n\t\t\t\t\t\t\t<div class=\"uael-post__terms-wrap\"><span class=\"uael-post__terms\"><span class=\"uael-listing__terms-link\">Evangelisation<\/span><\/span><\/div>\n\t\t\t\t\t\t<h4 class=\"uael-post__title\">\n\n\t\t\n\t\t\t\t\t\t<a href=\"https:\/\/ht-ost.com\/de\/spielplatz-holercani\/\" target=\"_self\">\n\t\t\t\tSpielplatz Holercani\t\t\t<\/a>\n\n\t\t\t\t<\/h4>\n\t\t\t\t\t<div class=\"uael-post__meta-data\">\n\t\t\t\t\t<span class=\"uael-post__date\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fa fa-calendar\"><\/i>\t\t\t\t\t\t\t\t\t\n\t\t\t15. September 2023\t\t<\/span>\n\t\t\t\t<\/div>\n\t\t\n\t\t<div class=\"uael-post__excerpt\">\n\t\t\tGottes Ma\u00dfarbeit In der letzten Zeitschrift berichteten wir von dem anstehenden Spielplatz-Baueinsatz im Ort Holercani im Osten Moldawiens. Nun k\u00f6nnen wir berichten: Der Einsatz war ...\t\t<\/div>\n\n\t\t\t\t\t<a class=\"uael-post__read-more elementor-button\" href=\"https:\/\/ht-ost.com\/de\/spielplatz-holercani\/\" target=\"_self\" aria-labelledby=\"uael-post-22165\">\n\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-icon elementor-align-icon-right\">\n\n\t\t\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-right\"><\/i>\n\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t<span class=\"elementor-button-text\" id=uael-post-22165>Weiterlesen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\n\t<\/div>\n\n<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\n\t\t<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t<div class=\"uael-post__footer\">\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Der kleine De-facto-Staat Transnistrien war lange Zeit Teil der damaligen Sowjetrepublik Moldau und befindet sich seit dem Zusammenbruch der Sowjetunion in einem bis heute eingefrorenen Konflikt mit der offiziellen Regierung Moldawiens &#8211; zum Leidwesen beider Seiten: Moldawien hat keinen Zugriff [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":21977,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"disabled","adv-header-id-meta":"","stick-header-meta":"disabled","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[19,18],"tags":[],"class_list":["post-21961","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-evangelisation","category-suppenkuechen"],"_links":{"self":[{"href":"https:\/\/ht-ost.com\/de\/wp-json\/wp\/v2\/posts\/21961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ht-ost.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ht-ost.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ht-ost.com\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ht-ost.com\/de\/wp-json\/wp\/v2\/comments?post=21961"}],"version-history":[{"count":12,"href":"https:\/\/ht-ost.com\/de\/wp-json\/wp\/v2\/posts\/21961\/revisions"}],"predecessor-version":[{"id":22269,"href":"https:\/\/ht-ost.com\/de\/wp-json\/wp\/v2\/posts\/21961\/revisions\/22269"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ht-ost.com\/de\/wp-json\/wp\/v2\/media\/21977"}],"wp:attachment":[{"href":"https:\/\/ht-ost.com\/de\/wp-json\/wp\/v2\/media?parent=21961"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ht-ost.com\/de\/wp-json\/wp\/v2\/categories?post=21961"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ht-ost.com\/de\/wp-json\/wp\/v2\/tags?post=21961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}